{"id":5577,"date":"2020-09-03T14:16:14","date_gmt":"2020-09-03T13:16:14","guid":{"rendered":"https:\/\/www.dendorfer-herrmann.de\/?page_id=5577"},"modified":"2021-05-21T10:16:42","modified_gmt":"2021-05-21T09:16:42","slug":"palettenboerse-vs-domaingrabber","status":"publish","type":"page","link":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/","title":{"rendered":"Palettenb\u00f6rse vs. Domaingrabber?"},"content":{"rendered":"<h2>Runde 2<\/h2>\n<h1>Palettenb\u00f6rse vs. Domaingrabber<\/h1>\n<div>\n<p>Ein \u00f6sterreichisches Unternehmen hat die Wortmarke \u201ePalettenb\u00f6rse\u201c in \u00d6sterreich angemeldet und verwendet folgende Domains:<\/p>\n<\/div>\n<ul>\n<li>\n<div>\n<p>palettenboerse.com<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>palettenboerse.at<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>palettenb\u00f6rse.at<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<div>\n<p>Nun hat sich ein Herr K. aus Deutschland die noch freie Domain mit Umlaut gesichert:<\/p>\n<\/div>\n<div>\n<div>\n<p><strong>palettenb\u00f6rse.com<\/strong><\/p>\n<\/div>\n<\/div>\n<div>\n<p><strong>Herr K.<\/strong> betreibt kein Palettenunternehmen und beabsichtigt auch keines zu betreiben. Es ist kein Eigeninteresse von Herrn K. an der Domain erkennbar. Nur gegen Zahlung eines Abl\u00f6sebetrags ist Herr K. bereit, die Domain an das \u00f6sterreichische Palettenunternehmen abzugeben.<\/p>\n<p><strong>Das \u00f6sterreichisches Unternehmen erw\u00e4gt eine Klage wegen Domain Grabbing.<\/strong><\/p>\n<p>Die Registrierungsstelle f\u00fcr *.com Domains befindet sich in den USA.<br \/>Das \u00f6sterreichische Palettenunternehmen ist nicht in Deutschland t\u00e4tig und hat dort die Marke nicht gesch\u00fctzt.<\/p>\n<\/div>\n<div>\n<h3>DOMAIN GRABBING<\/h3>\n<div>\n<p>Domain Grabbing kann in zwei Erscheinungsformen verwirklicht sein:<\/p>\n<ul>\n<li>Bei der Domainvermarktung bewirkt der Verletzer die Registrierung eines Zeichens als Domain in der (zumindest \u00fcberwiegenden) Absicht, vom Zeichenberechtigten einen finanziellen Vorteil f\u00fcr die \u00dcbertragung der Domain zu erlangen.<\/li>\n<li>Bei der Domainblockade wird eine Domain belegt, aber nicht oder nur zum Schein benutzt, um ein Vertriebshindernis f\u00fcr den Markeninhaber zu errichten.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<h3>WAS MEINEN SIE?<\/h3>\n<h5>In welchem Land kann die \u00f6sterreichische Firma Herrn K. auf Domain Grabbing klagen?<\/h5>\n<p>\n    <a href=\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/palettenboerse-vs-domaingrabber-aufloesung\/\">Aufl\u00f6sung zeigen<\/a>\n<\/p>\n<p><!--more--><br \/>\n<!-- {\"name\":\"rallye\",\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_top\":false,\"padding_remove_bottom\":false,\"padding\":\"xsmall\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"breadcrumbs\",\"props\":{\"show_home\":true,\"show_current\":false,\"home_text\":\"Home\"}}]}]}],\"modified\":\"2021-05-21T08:55:35.040Z\",\"name\":\"Breadcrumb\"},{\"type\":\"section\",\"props\":{\"style\":\"primary\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"image\":\"wp-content\\\/uploads\\\/sites\\\/8\\\/marken-img-02.jpg\",\"image_size\":\"cover\",\"media_background\":\"#1D1D1D\",\"media_overlay\":\"rgba(22, 22, 22, 0.27)\",\"css\":\".el-section * {text-shadow:2px 2px 2px rgba(0,0,0,0.5);}\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Runde 2\",\"margin_remove_top\":false,\"margin_remove_bottom\":true}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"content\":\"Palettenb\\u00f6rse vs. Domaingrabber\",\"title_style\":\"heading-medium\",\"margin_remove_bottom\":false,\"title_decoration\":\"line\",\"margin_remove_top\":true}}]}]}]},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Ein \\u00f6sterreichisches Unternehmen hat die Wortmarke \\u201ePalettenb\\u00f6rse\\u201c in \\u00d6sterreich angemeldet und verwendet folgende Domains:<\\\/p>\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_size\":\"\",\"list_marker\":\"circle\",\"list_marker_color\":\"primary\",\"content_style\":\"h5\"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>palettenboerse.com<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>palettenboerse.at<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>palettenb\\u00f6rse.at<\\\/p>\"}}]},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Nun hat sich ein Herr K. aus Deutschland die noch freie Domain mit Umlaut gesichert:<\\\/p>\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"circle\",\"content_style\":\"h5\"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p><strong>palettenb\\u00f6rse.com<\\\/strong><\\\/p>\"}}]},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><strong>Herr K.<\\\/strong> betreibt kein Palettenunternehmen und beabsichtigt auch keines zu betreiben. Es ist kein Eigeninteresse von Herrn K. an der Domain erkennbar. Nur gegen Zahlung eines Abl\\u00f6sebetrags ist Herr K. bereit, die Domain an das \\u00f6sterreichische Palettenunternehmen abzugeben.<\\\/p>\\n\n\n<p><strong>Das \\u00f6sterreichisches Unternehmen erw\\u00e4gt eine Klage wegen Domain Grabbing.<\\\/strong><\\\/p>\\n\n\n<p>Die Registrierungsstelle f\\u00fcr *.com Domains befindet sich in den USA.<br \\\/>Das \\u00f6sterreichische Palettenunternehmen ist nicht in Deutschland t\\u00e4tig und hat dort die Marke nicht gesch\\u00fctzt.<\\\/p>\"}}]}]}]},{\"type\":\"section\",\"props\":{\"style\":\"secondary\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"panel\",\"props\":{\"link_text\":\"Read more\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"left\",\"image_grid_width\":\"small\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"margin\":\"default\",\"title\":\"DOMAIN GRABBING\",\"content\":\"\n\n<p>Domain Grabbing kann in zwei Erscheinungsformen verwirklicht sein:<\\\/p>\\n\n\n<ul>\\n\n\n<li>Bei der Domainvermarktung bewirkt der Verletzer die Registrierung eines Zeichens als Domain in der (zumindest \\u00fcberwiegenden) Absicht, vom Zeichenberechtigten einen finanziellen Vorteil f\\u00fcr die \\u00dcbertragung der Domain zu erlangen.<\\\/li>\\n\n\n<li>Bei der Domainblockade wird eine Domain belegt, aber nicht oder nur zum Schein benutzt, um ein Vertriebshindernis f\\u00fcr den Markeninhaber zu errichten.<\\\/li>\\n<\\\/ul>\",\"icon\":\"info\",\"icon_color\":\"primary\"}}]}]}]},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"WAS MEINEN SIE?\",\"title_style\":\"h2\"}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h5\",\"content\":\"In welchem Land kann die \\u00f6sterreichische Firma Herrn K. auf Domain Grabbing klagen?\",\"title_decoration\":\"bullet\",\"class\":\" bluebullet\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\",\"class\":\"bluebutton\",\"button_size\":\"large\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"icon_align\":\"right\",\"content\":\"Aufl\\u00f6sung zeigen\",\"link\":\"dienstleistungen\\\/marken\\\/marken-rallye\\\/palettenboerse-vs-domaingrabber\\\/palettenboerse-vs-domaingrabber-aufloesung\",\"icon\":\"triangle-right\"}}]}]}]}]}],\"version\":\"2.4.14\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Runde 2 Palettenb\u00f6rse vs. Domaingrabber Ein \u00f6sterreichisches Unternehmen hat die Wortmarke \u201ePalettenb\u00f6rse\u201c in \u00d6sterreich angemeldet und verwendet folgende Domains: palettenboerse.com palettenboerse.at palettenb\u00f6rse.at Nun hat sich ein Herr K. aus Deutschland die noch freie Domain mit Umlaut gesichert: palettenb\u00f6rse.com Herr K. betreibt kein Palettenunternehmen und beabsichtigt auch keines zu betreiben. Es ist kein Eigeninteresse von Herrn [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4599,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5577","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palettenb\u00f6rse vs. Domaingrabber? - Patentanwalt Dipl.-Ing. Peter Herre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palettenb\u00f6rse vs. Domaingrabber? - Patentanwalt Dipl.-Ing. Peter Herre\" \/>\n<meta property=\"og:description\" content=\"Runde 2 Palettenb\u00f6rse vs. Domaingrabber Ein \u00f6sterreichisches Unternehmen hat die Wortmarke \u201ePalettenb\u00f6rse\u201c in \u00d6sterreich angemeldet und verwendet folgende Domains: palettenboerse.com palettenboerse.at palettenb\u00f6rse.at Nun hat sich ein Herr K. aus Deutschland die noch freie Domain mit Umlaut gesichert: palettenb\u00f6rse.com Herr K. betreibt kein Palettenunternehmen und beabsichtigt auch keines zu betreiben. Es ist kein Eigeninteresse von Herrn [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\" \/>\n<meta property=\"og:site_name\" content=\"Patentanwalt Dipl.-Ing. Peter Herre\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-21T09:16:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/\",\"url\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/\",\"name\":\"Palettenb\u00f6rse vs. Domaingrabber? - Patentanwalt Dipl.-Ing. Peter Herre\",\"isPartOf\":{\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/#website\"},\"datePublished\":\"2020-09-03T13:16:14+00:00\",\"dateModified\":\"2021-05-21T09:16:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leistungen\",\"item\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leistungen\",\"item\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marken\",\"item\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Marken-Rallye\",\"item\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Palettenb\u00f6rse vs. Domaingrabber?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/#website\",\"url\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/\",\"name\":\"Patentanwalt Dipl.-Ing. Peter Herre\",\"description\":\"Patentanwalt Dipl.-Ing. Peter Herre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palettenb\u00f6rse vs. Domaingrabber? - Patentanwalt Dipl.-Ing. Peter Herre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/","og_locale":"de_DE","og_type":"article","og_title":"Palettenb\u00f6rse vs. Domaingrabber? - Patentanwalt Dipl.-Ing. Peter Herre","og_description":"Runde 2 Palettenb\u00f6rse vs. Domaingrabber Ein \u00f6sterreichisches Unternehmen hat die Wortmarke \u201ePalettenb\u00f6rse\u201c in \u00d6sterreich angemeldet und verwendet folgende Domains: palettenboerse.com palettenboerse.at palettenb\u00f6rse.at Nun hat sich ein Herr K. aus Deutschland die noch freie Domain mit Umlaut gesichert: palettenb\u00f6rse.com Herr K. betreibt kein Palettenunternehmen und beabsichtigt auch keines zu betreiben. Es ist kein Eigeninteresse von Herrn [&hellip;]","og_url":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber","og_site_name":"Patentanwalt Dipl.-Ing. Peter Herre","article_modified_time":"2021-05-21T09:16:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/","url":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/","name":"Palettenb\u00f6rse vs. Domaingrabber? - Patentanwalt Dipl.-Ing. Peter Herre","isPartOf":{"@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/#website"},"datePublished":"2020-09-03T13:16:14+00:00","dateModified":"2021-05-21T09:16:42+00:00","breadcrumb":{"@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/palettenboerse-vs-domaingrabber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leistungen","item":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/"},{"@type":"ListItem","position":2,"name":"Leistungen","item":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/"},{"@type":"ListItem","position":3,"name":"Marken","item":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/"},{"@type":"ListItem","position":4,"name":"Marken-Rallye","item":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\/marken-rallye\/"},{"@type":"ListItem","position":5,"name":"Palettenb\u00f6rse vs. Domaingrabber?"}]},{"@type":"WebSite","@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/#website","url":"https:\/\/www.dendorfer-herrmann.de\/herre\/","name":"Patentanwalt Dipl.-Ing. Peter Herre","description":"Patentanwalt Dipl.-Ing. Peter Herre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dendorfer-herrmann.de\/herre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/pages\/5577"}],"collection":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/comments?post=5577"}],"version-history":[{"count":5,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/pages\/5577\/revisions"}],"predecessor-version":[{"id":27879,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/pages\/5577\/revisions\/27879"}],"up":[{"embeddable":true,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/pages\/4599"}],"wp:attachment":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/wp-json\/wp\/v2\/media?parent=5577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}