{"id":3192,"date":"2020-08-19T02:36:33","date_gmt":"2020-08-19T01:36:33","guid":{"rendered":"https:\/\/www.dendorfer-herrmann.de\/?page_id=3192"},"modified":"2024-07-26T00:35:27","modified_gmt":"2024-07-25T22:35:27","slug":"marken","status":"publish","type":"page","link":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken","title":{"rendered":"Marken"},"content":{"rendered":"<h2>EINE MARKE H\u00c4LT WORT<\/h2>\n<div>\n<p>Das Vertrauen Ihrer Kunden in Ihre Marke ist Ihr Kapital. Mit einer Marke sch\u00fctzen Sie Ihre Einzigartigkeit und festigen Ihre Position im Wettbewerb. Zum Pauschalpreis plus dem Service von <a href=\"https:\/\/www.dendorfer-herrmann.de\/\">patent.plus<\/a><\/p>\n<\/div>\n<ul>\n<li>\n<div>\n<p><a href=\"https:\/\/www.dendorfer-herrmann.de\/herre\/beitraege\/marken\/marken-rallye\" data-wplink-url-error=\"true\"><strong>Marken-Rallye:<\/strong> <\/a>Der unterhaltsame Einstieg ins Markenrecht<br \/>5 \u2013 20 Minuten pures Adrenalin!<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>\u201c<a href=\"https:\/\/www.dendorfer-herrmann.de\/herre\/beitraege\/marken\/hilfe-wir-haben-kein-budget\" data-wplink-url-error=\"true\"><strong>Hilfe, wir haben kein Budget!<\/strong><\/a>\u201c<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Do it yourself: <a href=\"https:\/\/www.dendorfer-herrmann.de\/herre\/beitraege\/marken\/leitfaden-marke-selbst-anmelden\"><strong>Leitfaden &#8211; Marke selbst anmelden<\/strong><\/a><\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Individuelles Angebot bei <strong>Patentanwalt Dipl.-Ing. Peter Herre<\/strong> einholen<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<div>\n<p>    <img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/grafik.png\" alt=\"\"><\/p>\n<p><img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/sites\/8\/2020\/08\/grafik.png\" alt=\"\"><\/p>\n<p><a href=\"\/herre\/wp-content\/uploads\/sites\/8\/2020\/08\/grafik.png\"><\/a><\/p>\n<\/div>\n<h5>Wir bieten drei unterschiedliche Dienstleistungspakete, um Ihre Marke anzumelden: <strong>BASIC,<\/strong> <strong>ADVANCED<\/strong> und <strong>PREMIUM<\/strong>. Bitte w\u00e4hlen Sie das Paket, das Ihre Bed\u00fcrfnisse optimal abdeckt.<\/h5>\n<div>Wir bieten drei unterschiedliche Dienstleistungspakete, um Ihre Marke anzumelden: <strong>BASIC,<\/strong> <strong>ADVANCED<\/strong> und <strong>PREMIUM<\/strong>. Bitte w\u00e4hlen Sie das Paket, das Ihre Bed\u00fcrfnisse optimal abdeckt.<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/eingabe.png\" alt=\"\"><\/p>\n<h3><span class='blue'>PLUS<\/span> VORABPR\u00dcFEN<\/h3>\n<div>\n<p>Wir beraten Sie im Markenrecht und ber\u00fccksichtigen dabei Wettbewerbsrecht und Urheberrecht. Wir f\u00fchren Recherchen im Handelsregister bzw. Firmenbuch durch und pr\u00fcfen Domain-Namen. Damit alles passt f\u00fcr Ihr Business.<\/p>\n<p>Bei <strong>BASIC<\/strong> beschr\u00e4nken wir unsere \u00dcberpr\u00fcfung darauf, ob bereits eine identische Marke eingetragen ist.<br \/>Mit <strong>ADVANCED<\/strong> erhalten Sie eine rudiment\u00e4re Einsch\u00e4tzung.<br \/>Mit <strong>PREMIUM<\/strong> erhalten Sie eine ausf\u00fchrliche Einsch\u00e4tzung inklusive Besprechung.<\/p>\n<\/div>\n<\/div>\n<hr>\n<div>\n<p>        <img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/gericht.png\" alt=\"\"><\/p>\n<h3><span class='blue'>PLUS<\/span> VERBESSERN<\/h3>\n<div>\n<p>Kein Business gleicht dem anderen. Mit uns stehen Ihnen Patentanw\u00e4lte f\u00fcr Ihre individuelle Beratung zur Verf\u00fcgung.<\/p>\n<p>Mit <strong>ADVANCED<\/strong> k\u00f6nnen Sie nach unserer R\u00fcckmeldung Ihren ersten Vorschlag optimieren. Bei <strong>PREMIUM<\/strong> beraten wir Sie dazu w\u00e4hrend unserer Besprechung. Bei Bedarf k\u00f6nnen Sie auf unsere umfassende anwaltliche Beratung zur\u00fcckgreifen. Sie haben sich f\u00fcr <strong>BASIC<\/strong> entschieden? Bei Bedarf k\u00f6nnen Sie an dieser Stelle ein Upgrade vornehmen. Sie bezahlen nur die Differenz zum Paket <strong>ADVANCED<\/strong> oder <strong>PREMIUM<\/strong>.<\/p>\n<\/div>\n<\/div>\n<hr>\n<div>\n<p>        <img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/anmeldung.png\" alt=\"\"><\/p>\n<h3><span class='blue'>PLUS<\/span> MARKENANMELDUNG<\/h3>\n<div>\n<p>Lassen Sie Ihre Markenanmeldung von Profis ausarbeiten und einreichen.<\/p>\n<p>Es ist mit einer durchschnittlichen Verfahrensdauer von etwa drei Monaten auszugehen, wenn das zust\u00e4ndige Markenamt keine Beanstandungen erhebt. Oft geht es auch deutlich schneller.<\/p>\n<p>Wir helfen Ihnen, im Falle eines erforderlichen Schriftwechsels mit dem zust\u00e4ndigen Markenamt rasch auf Eintragungshindernisse zu reagieren. Dabei k\u00f6nnen Sie auf unseren vollen anwaltlichen Service zur\u00fcckgreifen. Die damit verbundenen Kosten teilen wir Ihnen vorher mit.<\/p>\n<\/div>\n<\/div>\n<hr>\n<div>\n<p>        <img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/schutzrecht.png\" alt=\"\"><\/p>\n<h3><span class='blue'>PLUS<\/span> REGISTRIERT<\/h3>\n<div>\n<p>Wenn Ihre Marke registriert ist, erhalten Sie von uns eine Best\u00e4tigung \u00fcber die erfolgreiche Registrierung Ihrer Marke.<\/p>\n<p>Gerne unterst\u00fctzen wir Sie dabei, Rechte aus Ihrer registrierten Marke wahrzunehmen.<\/p>\n<\/div>\n<\/div>\n<hr>\n<div>\n<p>        <img decoding=\"async\" src=\"\/herre\/wp-content\/uploads\/world.png\" alt=\"\"><\/p>\n<h3>WAS KOSTET DAS ANMELDEN EINER MARKE?<\/h3>\n<div>\n<p>Die Kosten einer Markenanmeldung setzen sich aus den amtlichen Geb\u00fchren des zust\u00e4ndigen Markenamts und unseren Leistungen zusammen.<\/p>\n<p>Wieviel Sie in die Markenanmeldung investieren sollten, h\u00e4ngt davon ab, wie stark Sie sich gegen\u00fcber Mitbewerbern abgrenzen und ob Sie m\u00f6gliche Risiken Ihrer Markenanmeldung resultierend aus anderen Schutzrechten ber\u00fccksichtigen wollen.<\/p>\n<p>Mit uns haben Sie die Sicherheit, im Bedarfsfall auf unseren vollen anwaltlichen Service zur\u00fcckzugreifen.<\/p>\n<\/div>\n<\/div>\n<ul>\n<li>\n<h3>Deutschland<\/h3>\n<div>\n\n<table id=\"tablepress-3\" class=\"tablepress tablepress-id-3 uk-table uk-table-responsive marken-table\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">IHRE INVESTITION<\/td><td class=\"column-2\">BASIC<\/td><td class=\"column-3\">ADVANCED<\/td><td class=\"column-4\">PREMIUM<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Unser Honorar f\u00fcr die Ausarbeitung und Einreichung der Markenanmeldung in Deutschland (zuz\u00fcglich Umsatzsteuer)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>390 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>690 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>990 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Amtliche Anmeldegeb\u00fchren des Deutschen Patent- und Markenamts inklusive 3 Nizza-Klassen (Stand: Juli 2020)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>290 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>290 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>290 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Unser Honorar f\u00fcr die Pr\u00fcfung und Weiterleitung des Eintragungsbeschlusses bei erfolgreicher Registrierung (zuz\u00fcglich Umsatzsteuer)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>200 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>200 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>200 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\"><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/Ihr-erster-Schritt-zu-Marke-300x48-1.png\" alt=\"\" width=\"300\" height=\"48\" class=\"alignnone size-medium wp-image-4577\" \/><\/td><td class=\"column-2\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=BASIC&amp;Land=Deutschland\">Ausw\u00e4hlen<\/a><br \/>\n<\/td><td class=\"column-3\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=ADVANCED&amp;Land=Deutschland\">Ausw\u00e4hlen<\/a><br \/>\n<\/td><td class=\"column-4\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=PREMIUM&amp;Land=Deutschland\">Ausw\u00e4hlen<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3 from cache -->\n<\/div>\n<\/li>\n<li>\n<h3>\u00d6sterreich<\/h3>\n<div>\n\n<table id=\"tablepress-4\" class=\"tablepress tablepress-id-4 uk-table uk-table-responsive marken-table\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">IHRE INVESTITION<\/td><td class=\"column-2\">BASIC<\/td><td class=\"column-3\">ADVANCED<\/td><td class=\"column-4\">PREMIUM<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Unser Honorar f\u00fcr die Ausarbeitung und Einreichung der Markenanmeldung in \u00d6sterreich (zuz\u00fcglich Umsatzsteuer)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>390 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>690 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>990 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Amtliche Anmeldegeb\u00fchren des \u00d6sterreichischen Patentamts inklusive 3 Nizza-Klassen (Stand: Juli 2020)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>280 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>280 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>280 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Unser Honorar f\u00fcr die Pr\u00fcfung und Weiterleitung des Eintragungsbeschlusses bei erfolgreicher Registrierung (zuz\u00fcglich Umsatzsteuer)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>200 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>200 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>200 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\"><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/Ihr-erster-Schritt-zu-Marke-300x48-1.png\" alt=\"\" width=\"300\" height=\"48\" class=\"alignnone size-full wp-image-18961\" \/><\/td><td class=\"column-2\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=BASIC&amp;Land=\u00d6sterreich\">Ausw\u00e4hlen<\/a><\/td><td class=\"column-3\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=ADVANCED&amp;Land=\u00d6sterreich\">Ausw\u00e4hlen<\/a><\/td><td class=\"column-4\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=PREMIUM&amp;Land=\u00d6sterreich\">Ausw\u00e4hlen<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-4 from cache -->\n<\/div>\n<\/li>\n<li>\n<h3>Europ\u00e4ische Union<\/h3>\n<div>\n\n<table id=\"tablepress-5\" class=\"tablepress tablepress-id-5 uk-table uk-table-responsive marken-table\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">IHRE INVESTITION<\/td><td class=\"column-2\">BASIC<\/td><td class=\"column-3\">ADVANCED<\/td><td class=\"column-4\">PREMIUM<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Unser Honorar f\u00fcr die Ausarbeitung und Einreichung der Markenanmeldung in der Europ\u00e4ischen Union (zuz\u00fcglich Umsatzsteuer)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>490 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>890 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>1.190 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Amtliche Anmeldegeb\u00fchren des Amts der Europ\u00e4ischen Union f\u00fcr geistiges Eigentum inklusive 1 Nizza-Klasse (Stand: Juli 2020)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>850 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>850 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>850 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Amtliche Geb\u00fchr des Amts der Europ\u00e4ischen Union f\u00fcr geistiges Eigentum f\u00fcr die zweite Nizza-Klasse (Stand: Juli 2020)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>50 \u20ac<br \/>\nfalls erforderlich<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>50 \u20ac<br \/>\nfalls erforderlich<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>50 \u20ac<br \/>\nfalls erforderlich<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Amtliche Geb\u00fchr des Amts der Europ\u00e4ischen Union f\u00fcr geistiges Eigentum f\u00fcr jede weitere Nizza-Klasse (Stand: Juli 2020)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>150 \u20ac<br \/>\nfalls erforderlich<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>150 \u20ac<br \/>\nfalls erforderlich<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>150 \u20ac<br \/>\nfalls erforderlich<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Unser Honorar f\u00fcr die Pr\u00fcfung und Weiterleitung des Eintragungsbeschlusses bei erfolgreicher Registrierung (zuz\u00fcglich Umsatzsteuer)<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div>200 \u20ac<\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div>200 \u20ac<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div>200 \u20ac<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/Ihr-erster-Schritt-zu-Marke-300x48-1.png\" alt=\"\" width=\"300\" height=\"48\" class=\"alignnone size-full wp-image-18961\" \/><\/td><td class=\"column-2\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=BASIC&amp;Land=Europ\u00e4ische%20Union\">Ausw\u00e4hlen<\/a><\/td><td class=\"column-3\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=ADVANCED&amp;Land=Europ\u00e4ische%20Union\">Ausw\u00e4hlen<\/a><\/td><td class=\"column-4\"><a class=\"uk-button uk-button-secondary\" href=\"marken\/bestellen?Paket=PREMIUM&amp;Land=Europ\u00e4ische%20Union\">Ausw\u00e4hlen<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-5 from cache -->\n<\/div>\n<\/li>\n<li>\n<h3>International<\/h3>\n<div>\n<p>Wir registrieren Ihre Marke in \u00fcber 90 L\u00e4ndern bei der WIPO nach dem Madrider Abkommen \u00fcber die internationale Registrierung von Marken.<\/p>\n<p>Da dieser Vorgang sehr individuell im Umfang variiert, gibt es kein plus Fixpreis-Angebot. Wir bitten Sie, mit Patentanwalt Dipl.-Ing. Peter Herre einen kostenlosen Beratungstermin zu vereinbaren.<\/p>\n<p>Eine internationale Markenanmeldung fungiert als B\u00fcndel aus nationalen Marken mit erleichterter B\u00fcrokratie. Mit nur einem einzigen Antrag wird um Registrierung f\u00fcr das gesamte B\u00fcndel von Marken vor einer zentralen Stelle angesucht.<\/p>\n<p>Kontaktieren Sie uns: ph@patent.de (kostenlose Anfrage, wir rufen Sie gerne zur\u00fcck)<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<h2>Know How<\/h2>\n<div>\n<\/div>\n<div>\n<h3>\n<h1><center>Unsere Markenpakete im Detail<\/center><\/h1>\n<\/h3>\n<div>\n\n<table id=\"tablepress-6\" class=\"tablepress tablepress-id-6 uk-table uk-table-responsive marken-table\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Beschreibung<\/td><td class=\"column-2\">BASIC<\/td><td class=\"column-3\">ADVANCED<\/td><td class=\"column-4\">PREMIUM<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Beratung zum Waren- und Dienstleistungsverzeichnis: Sie beschreiben Ihren Gesch\u00e4ftsgegenstand inklusive der geplanten Erweiterungen Ihres Produkt- und Serviceangebots, das mit der Marke abgedeckt werden soll.<br \/>\nAuf dieser Basis erarbeiten wir unseren Vorschlag f\u00fcr die Waren und Dienstleistungen sowie deren Zuordnung zur jeweiligen Nizza-Klasse.<br \/>\n<br \/>\nIm Paketpreis sind bis zu 3 Nizza-Klassen (Europ\u00e4ische Union: 1 Nizza-Klasse) sowie bis zu 30 individuelle Eintragungen in das Waren- und Dienstleistungsverzeichnis enthalten.<br \/>\n<br \/>\nDie auf Ihr Gesch\u00e4ftsfeld abgestimmten Waren und Dienstleistungen bestimmen den markenrechtlichen Schutz und somit die Angriffsfl\u00e4che im Konfliktfall.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail<\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><\/br>per E-Mail oder telefonisch<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Klasseneinteilung und Erstellen des Waren- und Dienstleistungsverzeichnisses. Inkludiert sind bis zu 3 Nizza-Klassen (Europ\u00e4ische Union: 1 Nizza-Klasse).<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Identit\u00e4tsrecherche im Markenregister: Wir pr\u00fcfen, ob im Markenregister identische Marken in Bezug auf den Wortlaut existieren (graphische Bestandteile werden nicht verglichen) und bei ihnen eine Identit\u00e4t der Nizza-Klassen des Waren- und Dienstleistungsverzeichnisses gegeben ist.<br \/>\nFalls wir Treffer finden, erhalten Sie von uns eine Auflistung von eingetragenen und angemeldeten identischen Marken.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">\u00c4hnlichkeitsrecherche im Markenregister: Wir pr\u00fcfen, ob im Markenregister \u00e4hnliche Zeichen mit \u00e4hnlichem Waren- und Dienstleistungsverzeichnis eingetragen sind.<br \/>\nSie erhalten von uns eine Auflistung von eingetragenen und angemeldeten \u00e4hnlichen Marken.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">\u00c4hnlichkeitsrecherche nach nicht registrierten Marken: Wir pr\u00fcfen in weiteren Datenbanken, ob auch \u00e4hnliche nicht registrierte Marken und Gesch\u00e4ftsbezeichnungen auffindbar sind.<br \/>\nSie erhalten von uns eine Auflistung von nicht registrierten Marken und Gesch\u00e4ftsbezeichnungen am Markt.<br \/>\n<br \/>\nDiese Liste kann Ihnen Hinweise geben auf Risiken, die aus dem Wettbewerbsrecht entstehen k\u00f6nnen.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Kollisionsrisiko Markenrecht: Erkennen Sie besser m\u00f6gliche Konfliktfelder: Wir machen eine Einsch\u00e4tzung des potentiellen Kollisionsrisikos in Ihrem Marktumfeld.<br \/>\nDurch unsere anwaltliche Erfahrung k\u00f6nnen wir Sie bei der Einsch\u00e4tzung des Kollisionsrisikos mit bestehenden Marken unterst\u00fctzen.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Kollisionsrisiko Wettbewerbsrecht und Urheberrecht: Die \u00dcberpr\u00fcfung dieser Schutzrechte sollten Sie nicht vergessen!<br \/>\nIn der noch weiter gehenden Bewertung Ihrer gesamten markenrechtlichen Situation beziehen wir auch das Wettbewerbsrecht und das Urheberrecht mit ein.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Vorschl\u00e4ge zur Optimierung Ihrer Marke: Falls eine \u00dcberarbeitung Ihrer Marke ratsam ist, unterbreiten wir Ihnen Vorschl\u00e4ge zur Optimierung.<br \/>\nMit unserer anwaltlichen Erfahrung gewinnen Sie eine weitere Perspektive und k\u00f6nnen gegebenenfalls Ihre Marke entsprechend ab\u00e4ndern.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Einsch\u00e4tzung der Eintragungsf\u00e4higkeit: Wir fassen die Ergebnisse unserer Recherche und Risikobewertung kurz zusammen, damit Sie eine rudiment\u00e4re Einsch\u00e4tzung der Eintragungsf\u00e4higkeit Ihrer gew\u00fcnschten Marke erhalten.<br \/>\nFalls wir Zweifel haben, ob das zust\u00e4ndige Markenamt Ihre Marke eintragen wird, erhalten Sie von uns umgehend R\u00fcckmeldung. Wir kl\u00e4ren Sie dar\u00fcber auf, welche Schutzhindernisse Ihrer Markenanmeldung entgegenstehen k\u00f6nnten.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail<\/td><td class=\"column-3\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail<\/td><td class=\"column-4\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail oder telefonisch<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">R\u00fcckmeldung zur geographischen Abdeckung: Nicht nur Ihre Absatzm\u00e4rkte, sondern auch Herstellungs- und Angebotsorte haben Einfluss darauf, in welchen L\u00e4ndern die Anmeldung Ihrer Marke zu empfehlen ist. Wir geben Ihnen R\u00fcckmeldung, ob eine Markenanmeldung in weiteren L\u00e4ndern anzuraten w\u00e4re.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail<\/td><td class=\"column-3\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail<\/td><td class=\"column-4\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail oder telefonisch<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Besprechen Ihrer Markenanmeldestrategie: Sprechen Sie \u00fcber Ihre Expansionspl\u00e4ne in andere L\u00e4nder. Denn sie beeinflussen bereits die Anmeldung der ersten Marke. Wir beraten Sie \u00fcber die optimale Markenanmeldestrategie.<br \/>\nPassen Sie Ihre Markenstrategie voll den sich bietenden internationalen M\u00f6glichkeiten an.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>telefonisch<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Ab\u00e4ndern Ihrer Marke und erneute Pr\u00fcfung: Stellt sich die Situation Ihrer Wunschmarke nach unserem R\u00fcckmelden f\u00fcr Sie neu dar, k\u00f6nnen Sie Ihren ersten Markenvorschlag einmalig ab\u00e4ndern und optimieren. Wir pr\u00fcfen dann die \u00fcberarbeitete Marke erneut.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div uk-icon=\"icon:close;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"><\/div><br\/>per E-Mail oder telefonisch<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Paket-Upgrade: Stellt sich die Situation Ihrer Wunschmarke nach unserer R\u00fcckmeldung f\u00fcr Sie neu dar, ist ein Wechsel in ein gr\u00f6\u00dferes Paket oder in eine individuelle Beratung m\u00f6glich. Sie bezahlen dabei nur den Differenzbetrag.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Ausarbeiten der Markenanmeldung: Wir legen Ihnen die ausgearbeitete Markenanmeldung vor und Sie best\u00e4tigen diese. So haben Sie die Kontrolle \u00fcber die Markenanmeldung.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Einreichen der Markenanmeldung: Nach Ihrer Freigabe reichen wir die Markenanmeldung beim zust\u00e4ndigen Markenamt ein und leiten die Eingangsbest\u00e4tigung an Sie weiter.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Weiterleiten von Amtsbescheiden: Bescheide des Markenamts leiten wir an Sie weiter. Die kurze Kommentierung und Weiterleitung eines ersten Bescheides ist im Honorar enthalten. F\u00fcr die Kommentierung und Weiterleitung weiterer Bescheide, die Erwiderung von Bescheiden sowie f\u00fcr Rechtsmittel oder Widerspruchsverfahren steht Ihnen unser individueller Service zur Verf\u00fcgung.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Weiterleiten des Eintragungsbeschlusses: Wir pr\u00fcfen den Beschluss des Markenamts \u00fcber die Eintragung der Marke in das Markenregister und leiten diesen an Sie weiter.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Vertretung vor dem Markenamt: Als Ihr Vertreter vor dem jeweiligen Markenamt nehmen wir w\u00e4hrend der Laufzeit der Marke Schriftst\u00fccke entgegen, kommentieren diese kurz und leiten diese an Sie gegen Kostenberechnung weiter.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Fristen\u00fcberwachung \u2013 ein Markenleben lang: Wir erinnern Sie rechtzeitig an die Verl\u00e4ngerung Ihres Markenschutzes.<\/td><td class=\"column-2\"><div class=\"mini-header\">BASIC<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-3\"><div class=\"mini-header\">ADVANCED<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td><td class=\"column-4\"><div class=\"mini-header\">PREMIUM<\/div><div class=\"blue\" uk-icon=\"icon:check;ratio:2\"\/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-6 from cache -->\n<\/div>\n<\/div>\n<h1>Weitere Leistungen im Markenrecht<\/h1>\n<ul>\n<li>\n<h3>VERTRETUNG UND FRIST\u00dcBERWACHUNG DER VERL\u00c4NGERUNG<\/h3>\n<div>\n<p>Als Ihr Vertreter nehmen wir w\u00e4hrend der Laufzeit der Marke Schriftst\u00fccke entgegen, kommentieren diese kurz und leiten sie an Sie weiter. Wir erinnern Sie an die rechtzeitige Verl\u00e4ngerung Ihres Markenschutzes. Dieser Service ist bereits in allen unseren Paketen enthalten.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>MARKENMONITORING PLUS<\/h3>\n<div>\n<p>Wir \u00fcberpr\u00fcfen alle drei Monate, ob zwischenzeitlich eine j\u00fcngere Marke angemeldet wurde, die der Ihren \u00e4hnlich ist. Damit Sie schnell genug reagieren und bei Bedarf Gegenma\u00dfnahmen einleiten k\u00f6nnen.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>WIDERSPRUCHSVERFAHREN<\/h3>\n<div>\n<p>Wurde eine j\u00fcngere Marke angemeldet, die der Ihren \u00e4hnlich ist, f\u00fchren wir ein Widerspruchsverfahren gegen die j\u00fcngere Marke durch.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>L\u00d6SCHUNGSVERFAHREN<\/h3>\n<div>\n<p>M\u00f6chten Sie die L\u00f6schung einer anderen Marke beantragen, f\u00fchren wir f\u00fcr Sie ein L\u00f6schungsverfahren durch.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>ABGRENZUNGSVEREINBARUNGEN<\/h3>\n<div>\n<p>Ihre Marke ist der Marke eines anderen Marktteilnehmers \u00e4hnlich? Regeln Sie in einer Abgrenzungsvereinbarung die friedliche Koexistenz beider Marken. Legen Sie gemeinsam fest, f\u00fcr welche Waren und Dienstleistungen Sie Ihre Marke nutzen d\u00fcrfen.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>LIZENZVERTR\u00c4GE<\/h3>\n<div>\n<p>Ein Dritter m\u00f6chte Ihre Marke nutzen? Sie m\u00f6chen eine bestehende Marke nutzen? Wir k\u00fcmmern uns darum.<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<p><!--more--><br \/>\n<!-- {\"name\":\"MARKEN\",\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_top\":false,\"padding_remove_bottom\":false,\"padding\":\"xsmall\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"breadcrumbs\",\"props\":{\"show_home\":true,\"show_current\":true,\"home_text\":\"Home\"}}]}]}],\"modified\":\"2021-05-21T08:55:35.040Z\",\"name\":\"Breadcrumb\"},{\"type\":\"section\",\"props\":{\"style\":\"muted\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_top\":false,\"padding_remove_bottom\":false,\"padding\":\"xsmall\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"EINE MARKE H\\u00c4LT WORT\",\"title_style\":\"heading-small\",\"title_decoration\":\"line\",\"margin_remove_top\":false}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Das Vertrauen Ihrer Kunden in Ihre Marke ist Ihr Kapital. Mit einer Marke sch\\u00fctzen Sie Ihre Einzigartigkeit und festigen Ihre Position im Wettbewerb. Zum Pauschalpreis plus dem Service von <a href=\\\"https:\\\/\\\/www.dendorfer-herrmann.de\\\/\\\">patent.plus<\\\/a><\\\/p>\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p><a href=\\\"beitraege\\\/marken\\\/marken-rallye\\\" data-wplink-url-error=\\\"true\\\"><strong>Marken-Rallye:<\\\/strong> <\\\/a>Der unterhaltsame Einstieg ins Markenrecht<br \\\/>5 \\u2013 20 Minuten pures Adrenalin!<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>\\u201c<a href=\\\"beitraege\\\/marken\\\/hilfe-wir-haben-kein-budget\\\" data-wplink-url-error=\\\"true\\\"><strong>Hilfe, wir haben kein Budget!<\\\/strong><\\\/a>\\u201c<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Do it yourself: <a href=\\\"beitraege\\\/marken\\\/leitfaden-marke-selbst-anmelden\\\"><strong>Leitfaden - Marke selbst anmelden<\\\/strong><\\\/a><\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Individuelles Angebot bei <strong>Patentanwalt Dipl.-Ing. Peter Herre<\\\/strong> einholen<\\\/p>\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"gallery\",\"props\":{\"show_title\":false,\"show_meta\":false,\"show_content\":false,\"show_link\":false,\"show_hover_image\":false,\"grid_default\":\"1\",\"grid_medium\":\"\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"overlay_mode\":\"cover\",\"overlay_hover\":false,\"overlay_style\":\"\",\"text_color\":\"\",\"overlay_position\":\"center\",\"overlay_transition\":\"fade\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"link_text\":\"\",\"link_style\":\"default\",\"text_align\":\"center\",\"margin\":\"default\",\"item_animation\":true,\"lightbox\":true,\"lightbox_image_orientation\":false,\"item_maxwidth\":\"medium\",\"css\":\"@media only screen and (max-width: 875px) {\\n    .el-image{width:150px; height:auto; display:block; margin:0 25%;}\\n}\",\"parallax_easing\":\"1\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/grafik.png\",\"hover_image\":\"wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/08\\\/grafik.png\",\"link\":\"wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/08\\\/grafik.png\"}}]}]}]}],\"name\":\"Intro\"},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_top\":false,\"padding\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h5\",\"content\":\"Wir bieten drei unterschiedliche Dienstleistungspakete, um Ihre Marke anzumelden: <strong>BASIC,<\\\/strong> <strong>ADVANCED<\\\/strong> und <strong>PREMIUM<\\\/strong>. Bitte w\\u00e4hlen Sie das Paket, das Ihre Bed\\u00fcrfnisse optimal abdeckt.\",\"visibility\":\"hidden-s\"}},{\"type\":\"headline\",\"props\":{\"title_element\":\"div\",\"content\":\"Wir bieten drei unterschiedliche Dienstleistungspakete, um Ihre Marke anzumelden: <strong>BASIC,<\\\/strong> <strong>ADVANCED<\\\/strong> und <strong>PREMIUM<\\\/strong>. Bitte w\\u00e4hlen Sie das Paket, das Ihre Bed\\u00fcrfnisse optimal abdeckt.\",\"title_style\":\"h3\",\"visibility\":\"s\"}},{\"type\":\"panel\",\"props\":{\"link_text\":\"Read more\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"left\",\"image_grid_width\":\"medium\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"margin\":\"medium\",\"content\":\"\n\n<p>Wir beraten Sie im Markenrecht und ber\\u00fccksichtigen dabei Wettbewerbsrecht und Urheberrecht. Wir f\\u00fchren Recherchen im Handelsregister bzw. Firmenbuch durch und pr\\u00fcfen Domain-Namen. Damit alles passt f\\u00fcr Ihr Business.<\\\/p>\\n\n\n<p>Bei <strong>BASIC<\\\/strong> beschr\\u00e4nken wir unsere \\u00dcberpr\\u00fcfung darauf, ob bereits eine identische Marke eingetragen ist.<br \\\/>Mit <strong>ADVANCED<\\\/strong> erhalten Sie eine rudiment\\u00e4re Einsch\\u00e4tzung.<br \\\/>Mit <strong>PREMIUM<\\\/strong> erhalten Sie eine ausf\\u00fchrliche Einsch\\u00e4tzung inklusive Besprechung.<\\\/p>\",\"title\":\"<span class='blue'>PLUS<\\\/span> VORABPR\\u00dcFEN\",\"image\":\"wp-content\\\/uploads\\\/eingabe.png\",\"css\":\"@media only screen and (max-width: 875px) {\\n    .el-image{width:150px; height:auto; display:block; margin:0 auto;}\\n}\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"margin\":\"medium\"}},{\"type\":\"panel\",\"props\":{\"link_text\":\"Read more\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"right\",\"image_grid_width\":\"medium\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"margin\":\"default\",\"content\":\"\n\n<p>Kein Business gleicht dem anderen. Mit uns stehen Ihnen Patentanw\\u00e4lte f\\u00fcr Ihre individuelle Beratung zur Verf\\u00fcgung.<\\\/p>\\n\n\n<p>Mit <strong>ADVANCED<\\\/strong> k\\u00f6nnen Sie nach unserer R\\u00fcckmeldung Ihren ersten Vorschlag optimieren. Bei <strong>PREMIUM<\\\/strong> beraten wir Sie dazu w\\u00e4hrend unserer Besprechung. Bei Bedarf k\\u00f6nnen Sie auf unsere umfassende anwaltliche Beratung zur\\u00fcckgreifen. Sie haben sich f\\u00fcr <strong>BASIC<\\\/strong> entschieden? Bei Bedarf k\\u00f6nnen Sie an dieser Stelle ein Upgrade vornehmen. Sie bezahlen nur die Differenz zum Paket <strong>ADVANCED<\\\/strong> oder <strong>PREMIUM<\\\/strong>.<\\\/p>\",\"title\":\"<span class='blue'>PLUS<\\\/span> VERBESSERN\",\"image\":\"wp-content\\\/uploads\\\/gericht.png\",\"css\":\"@media only screen and (max-width: 875px) {\\n    .el-image{width:150px; height:auto; display:block; margin:0 auto;}\\n}\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"margin\":\"medium\"}},{\"type\":\"panel\",\"props\":{\"link_text\":\"Read more\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"left\",\"image_grid_width\":\"medium\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"margin\":\"default\",\"content\":\"\n\n<p>Lassen Sie Ihre Markenanmeldung von Profis ausarbeiten und einreichen.<\\\/p>\\n\n\n<p>Es ist mit einer durchschnittlichen Verfahrensdauer von etwa drei Monaten auszugehen, wenn das zust\\u00e4ndige Markenamt keine Beanstandungen erhebt. Oft geht es auch deutlich schneller.<\\\/p>\\n\n\n<p>Wir helfen Ihnen, im Falle eines erforderlichen Schriftwechsels mit dem zust\\u00e4ndigen Markenamt rasch auf Eintragungshindernisse zu reagieren. Dabei k\\u00f6nnen Sie auf unseren vollen anwaltlichen Service zur\\u00fcckgreifen. Die damit verbundenen Kosten teilen wir Ihnen vorher mit.<\\\/p>\",\"title\":\"<span class='blue'>PLUS<\\\/span> MARKENANMELDUNG\",\"image\":\"wp-content\\\/uploads\\\/anmeldung.png\",\"css\":\"@media only screen and (max-width: 875px) {\\n    .el-image{width:150px; height:auto; display:block; margin:0 auto;}\\n}\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"margin\":\"medium\"}},{\"type\":\"panel\",\"props\":{\"link_text\":\"Read more\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"right\",\"image_grid_width\":\"medium\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"margin\":\"\",\"content\":\"\n\n<p>Wenn Ihre Marke registriert ist, erhalten Sie von uns eine Best\\u00e4tigung \\u00fcber die erfolgreiche Registrierung Ihrer Marke.<\\\/p>\\n\n\n<p>Gerne unterst\\u00fctzen wir Sie dabei, Rechte aus Ihrer registrierten Marke wahrzunehmen.<\\\/p>\",\"title\":\"<span class='blue'>PLUS<\\\/span> REGISTRIERT\",\"image\":\"wp-content\\\/uploads\\\/schutzrecht.png\",\"css\":\"@media only screen and (max-width: 875px) {\\n    .el-image{width:150px; height:auto; display:block; margin:0 auto;}\\n}\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"margin\":\"large\"}},{\"type\":\"panel\",\"props\":{\"link_text\":\"Read more\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"left\",\"image_grid_width\":\"medium\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"margin\":\"large\",\"content\":\"\n\n<p>Die Kosten einer Markenanmeldung setzen sich aus den amtlichen Geb\\u00fchren des zust\\u00e4ndigen Markenamts und unseren Leistungen zusammen.<\\\/p>\\n\n\n<p>Wieviel Sie in die Markenanmeldung investieren sollten, h\\u00e4ngt davon ab, wie stark Sie sich gegen\\u00fcber Mitbewerbern abgrenzen und ob Sie m\\u00f6gliche Risiken Ihrer Markenanmeldung resultierend aus anderen Schutzrechten ber\\u00fccksichtigen wollen.<\\\/p>\\n\n\n<p>Mit uns haben Sie die Sicherheit, im Bedarfsfall auf unseren vollen anwaltlichen Service zur\\u00fcckzugreifen.<\\\/p>\",\"title\":\"WAS KOSTET DAS ANMELDEN EINER MARKE?\",\"image\":\"wp-content\\\/uploads\\\/world.png\",\"css\":\"@media only screen and (max-width: 875px) {\\n    .el-image{width:150px; height:auto; display:block; margin:0 auto;}\\n}\"}}]}]}],\"name\":\"Markenpakete\"},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_bottom\":true,\"overlap\":false},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"position_sticky_breakpoint\":\"m\",\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"switcher\",\"props\":{\"show_title\":false,\"show_meta\":true,\"show_content\":true,\"show_image\":true,\"show_link\":true,\"show_label\":false,\"show_thumbnail\":false,\"switcher_animation\":\"fade\",\"switcher_height\":true,\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"top\",\"image_grid_width\":\"1-2\",\"image_grid_breakpoint\":\"m\",\"link_text\":\"Read more\",\"link_style\":\"default\",\"margin\":\"default\",\"css\":\"@media only screen and (max-width: 875px){\\n.row-1 td:nth-child(n+1){display:none;}\\n}\\n\\n@media only screen and (min-width: 875px){\\n.mini-header{display:none;}\\n}\\n.el-element .mini-header{font-size:65%;}\",\"nav\":\"subnav-pill\",\"thumbnav_width\":\"100\",\"thumbnav_height\":\"75\",\"thumbnav_svg_color\":\"emphasis\",\"nav_position\":\"top\",\"nav_align\":\"left\",\"nav_grid_width\":\"auto\",\"nav_grid_breakpoint\":\"m\"},\"children\":[{\"type\":\"switcher_item\",\"props\":{\"title\":\"Deutschland\",\"content\":\"\n\n<p>[table id=3 \\\/]<\\\/p>\",\"label\":\"\",\"link\":\"\"}},{\"type\":\"switcher_item\",\"props\":{\"title\":\"\\u00d6sterreich\",\"content\":\"\n\n<p>[table id=4 \\\/]<\\\/p>\",\"label\":\"\",\"link\":\"\"}},{\"type\":\"switcher_item\",\"props\":{\"title\":\"Europ\\u00e4ische Union\",\"content\":\"\n\n<p>[table id=5 \\\/]<\\\/p>\"}},{\"type\":\"switcher_item\",\"props\":{\"title\":\"International\",\"content\":\"\n\n<p>Wir registrieren Ihre Marke in \\u00fcber 90 L\\u00e4ndern bei der WIPO nach dem Madrider Abkommen \\u00fcber die internationale Registrierung von Marken.<\\\/p>\\n\n\n<p>Da dieser Vorgang sehr individuell im Umfang variiert, gibt es kein plus Fixpreis-Angebot. Wir bitten Sie, mit Patentanwalt Dipl.-Ing. Peter Herre einen kostenlosen Beratungstermin zu vereinbaren.<\\\/p>\\n\n\n<p>Eine internationale Markenanmeldung fungiert als B\\u00fcndel aus nationalen Marken mit erleichterter B\\u00fcrokratie. Mit nur einem einzigen Antrag wird um Registrierung f\\u00fcr das gesamte B\\u00fcndel von Marken vor einer zentralen Stelle angesucht.<\\\/p>\\n\n\n<p>Kontaktieren Sie uns: ph@patent.de (kostenlose Anfrage, wir rufen Sie gerne zur\\u00fcck)<\\\/p>\"}}]}]}]}],\"name\":\"Preise\"},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Know How\",\"text_align\":\"center\"}},{\"type\":\"grid\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_image\":true,\"show_link\":true,\"grid_default\":\"1\",\"grid_medium\":\"3\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"top\",\"image_grid_width\":\"1-2\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_text\":\"Weiterlesen\",\"link_style\":\"text\",\"margin\":\"default\",\"item_animation\":true,\"panel_link\":true,\"panel_style\":\"card-default\",\"title_style\":\"h4\",\"image_width\":\"370\",\"image_height\":\"185\",\"panel_image_no_padding\":true,\"panel_padding\":\"default\",\"parallax_easing\":\"1\"},\"children\":[{\"type\":\"grid_item\",\"source\":{\"query\":{\"name\":\"posts.customPosts\",\"arguments\":{\"terms\":[33],\"offset\":0,\"order\":\"title\",\"order_direction\":\"ASC\",\"order_alphanum\":true}},\"props\":{\"title\":{\"filters\":{\"search\":\"\"},\"name\":\"title\"},\"content\":{\"filters\":{\"search\":\"\"},\"name\":\"excerpt\"},\"image\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.url\"},\"image_alt\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.alt\"},\"link\":{\"filters\":{\"search\":\"\"},\"name\":\"link\"}}}}]}]}]}],\"name\":\"Know How\"},{\"type\":\"section\",\"props\":{\"style\":\"muted\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_top\":false},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"position_sticky_breakpoint\":\"m\",\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"accordion\",\"props\":{\"show_image\":true,\"show_link\":true,\"collapsible\":false,\"content_column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"top\",\"image_grid_width\":\"1-2\",\"image_grid_breakpoint\":\"m\",\"link_text\":\"Read more\",\"link_style\":\"default\",\"position_z_index\":\"1\",\"multiple\":true},\"children\":[{\"type\":\"accordion_item\",\"props\":{\"title\":\"\n\n<h1><center>Unsere Markenpakete im Detail<\\\/center><\\\/h1>\",\"content\":\"\n\n<p>[table id=6 \\\/]<\\\/p>\"}}]}]}]}],\"name\":\"Markenpakete im Detail\"},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"content\":\"Weitere Leistungen im Markenrecht\",\"text_align\":\"center\"}}]}]}],\"name\":\"Weitere Leistungen im Markenrecht\"},{\"type\":\"section\",\"props\":{\"style\":\"muted\",\"width\":\"default\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"grid\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_image\":true,\"show_link\":true,\"grid_default\":\"1\",\"grid_medium\":\"\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":\"50\",\"image_align\":\"left\",\"image_grid_width\":\"auto\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_text\":\"Read more\",\"link_style\":\"default\",\"margin\":\"default\",\"item_animation\":true,\"parallax_easing\":\"1\"},\"children\":[{\"type\":\"grid_item\",\"props\":{\"icon\":\"future\",\"title\":\"VERTRETUNG UND FRIST\\u00dcBERWACHUNG DER VERL\\u00c4NGERUNG\",\"content\":\"\n\n<p>Als Ihr Vertreter nehmen wir w\\u00e4hrend der Laufzeit der Marke Schriftst\\u00fccke entgegen, kommentieren diese kurz und leiten sie an Sie weiter. Wir erinnern Sie an die rechtzeitige Verl\\u00e4ngerung Ihres Markenschutzes. Dieser Service ist bereits in allen unseren Paketen enthalten.<\\\/p>\"}},{\"type\":\"grid_item\",\"props\":{\"icon\":\"plus-circle\",\"title\":\"MARKENMONITORING PLUS\",\"content\":\"\n\n<p>Wir \\u00fcberpr\\u00fcfen alle drei Monate, ob zwischenzeitlich eine j\\u00fcngere Marke angemeldet wurde, die der Ihren \\u00e4hnlich ist. Damit Sie schnell genug reagieren und bei Bedarf Gegenma\\u00dfnahmen einleiten k\\u00f6nnen.<\\\/p>\"}},{\"type\":\"grid_item\",\"props\":{\"title\":\"WIDERSPRUCHSVERFAHREN\",\"content\":\"\n\n<p>Wurde eine j\\u00fcngere Marke angemeldet, die der Ihren \\u00e4hnlich ist, f\\u00fchren wir ein Widerspruchsverfahren gegen die j\\u00fcngere Marke durch.<\\\/p>\",\"icon\":\"commenting\"}},{\"type\":\"grid_item\",\"props\":{\"title\":\"L\\u00d6SCHUNGSVERFAHREN\",\"content\":\"\n\n<p>M\\u00f6chten Sie die L\\u00f6schung einer anderen Marke beantragen, f\\u00fchren wir f\\u00fcr Sie ein L\\u00f6schungsverfahren durch.<\\\/p>\",\"icon\":\"close\"}},{\"type\":\"grid_item\",\"props\":{\"title\":\"ABGRENZUNGSVEREINBARUNGEN\",\"content\":\"\n\n<p>Ihre Marke ist der Marke eines anderen Marktteilnehmers \\u00e4hnlich? Regeln Sie in einer Abgrenzungsvereinbarung die friedliche Koexistenz beider Marken. Legen Sie gemeinsam fest, f\\u00fcr welche Waren und Dienstleistungen Sie Ihre Marke nutzen d\\u00fcrfen.<\\\/p>\",\"icon\":\"pencil\"}},{\"type\":\"grid_item\",\"props\":{\"title\":\"LIZENZVERTR\\u00c4GE\",\"content\":\"\n\n<p>Ein Dritter m\\u00f6chte Ihre Marke nutzen? Sie m\\u00f6chen eine bestehende Marke nutzen? Wir k\\u00fcmmern uns darum.<\\\/p>\",\"icon\":\"users\"}}]}]}]}]}],\"version\":\"3.0.4\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EINE MARKE H\u00c4LT WORT Das Vertrauen Ihrer Kunden in Ihre Marke ist Ihr Kapital. Mit einer Marke sch\u00fctzen Sie Ihre Einzigartigkeit und festigen Ihre Position im Wettbewerb. Zum Pauschalpreis plus dem Service von patent.plus Marken-Rallye: Der unterhaltsame Einstieg ins Markenrecht5 \u2013 20 Minuten pures Adrenalin! \u201cHilfe, wir haben kein Budget!\u201c Do it yourself: Leitfaden &#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":11163,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3192","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marken - Patentanwalt Dipl.-Ing. Peter Herre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/dienstleistungen\/marken\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marken - Patentanwalt Dipl.-Ing. Peter Herre\" \/>\n<meta property=\"og:description\" content=\"EINE MARKE H\u00c4LT WORT Das Vertrauen Ihrer Kunden in Ihre Marke ist Ihr Kapital. Mit einer Marke sch\u00fctzen Sie Ihre Einzigartigkeit und festigen Ihre Position im Wettbewerb. Zum Pauschalpreis plus dem Service von patent.plus Marken-Rallye: Der unterhaltsame Einstieg ins Markenrecht5 \u2013 20 Minuten pures Adrenalin! \u201cHilfe, wir haben kein Budget!\u201c Do it yourself: Leitfaden &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\" \/>\n<meta property=\"og:site_name\" content=\"Patentanwalt Dipl.-Ing. Peter Herre\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T22:35:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\",\"url\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\",\"name\":\"Marken - Patentanwalt Dipl.-Ing. Peter Herre\",\"isPartOf\":{\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/#website\"},\"datePublished\":\"2020-08-19T01:36:33+00:00\",\"dateModified\":\"2024-07-25T22:35:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leistungen\",\"item\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/dienstleistungen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/#website\",\"url\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/\",\"name\":\"Patentanwalt Dipl.-Ing. Peter Herre\",\"description\":\"Patentanwalt Dipl.-Ing. Peter Herre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marken - Patentanwalt Dipl.-Ing. Peter Herre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/dienstleistungen\/marken\/","og_locale":"en_US","og_type":"article","og_title":"Marken - Patentanwalt Dipl.-Ing. Peter Herre","og_description":"EINE MARKE H\u00c4LT WORT Das Vertrauen Ihrer Kunden in Ihre Marke ist Ihr Kapital. Mit einer Marke sch\u00fctzen Sie Ihre Einzigartigkeit und festigen Ihre Position im Wettbewerb. Zum Pauschalpreis plus dem Service von patent.plus Marken-Rallye: Der unterhaltsame Einstieg ins Markenrecht5 \u2013 20 Minuten pures Adrenalin! \u201cHilfe, wir haben kein Budget!\u201c Do it yourself: Leitfaden &#8211; [&hellip;]","og_url":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken","og_site_name":"Patentanwalt Dipl.-Ing. Peter Herre","article_modified_time":"2024-07-25T22:35:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken","url":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken","name":"Marken - Patentanwalt Dipl.-Ing. Peter Herre","isPartOf":{"@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/#website"},"datePublished":"2020-08-19T01:36:33+00:00","dateModified":"2024-07-25T22:35:27+00:00","breadcrumb":{"@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/dienstleistungen\/marken#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leistungen","item":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/dienstleistungen\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/services\/"},{"@type":"ListItem","position":3,"name":"Marken"}]},{"@type":"WebSite","@id":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/#website","url":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/","name":"Patentanwalt Dipl.-Ing. Peter Herre","description":"Patentanwalt Dipl.-Ing. Peter Herre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/pages\/3192"}],"collection":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/comments?post=3192"}],"version-history":[{"count":23,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/pages\/3192\/revisions"}],"predecessor-version":[{"id":37696,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/pages\/3192\/revisions\/37696"}],"up":[{"embeddable":true,"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/pages\/11163"}],"wp:attachment":[{"href":"https:\/\/www.dendorfer-herrmann.de\/herre\/en\/wp-json\/wp\/v2\/media?parent=3192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}